{"id":96,"count":10,"description":"","link":"https:\/\/ntdecor.vn\/vi\/category\/thiet-ke-vi\/","name":"Thi\u1ebft k\u1ebf","slug":"thiet-ke-vi","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ntdecor.vn\/vi\/wp-json\/wp\/v2\/categories\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ntdecor.vn\/vi\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ntdecor.vn\/vi\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ntdecor.vn\/vi\/wp-json\/wp\/v2\/posts?categories=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}